{"id":770,"date":"2024-07-16T07:39:27","date_gmt":"2024-07-16T07:39:27","guid":{"rendered":"http:\/\/source.wpopal.com\/industras\/?post_type=project&#038;p=770"},"modified":"2025-04-23T11:50:17","modified_gmt":"2025-04-23T15:50:17","slug":"transforming-manufacturing-with-smart-industry-robot-arms","status":"publish","type":"project","link":"https:\/\/conceptsk1.com\/filtrationlab-dev\/project\/transforming-manufacturing-with-smart-industry-robot-arms\/","title":{"rendered":"Transforming Manufacturing with Smart Industry Robot Arms"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"770\" class=\"elementor elementor-770\" data-elementor-post-type=\"project\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e0c6a7 e-flex e-con-boxed e-con e-parent\" data-id=\"2e0c6a7\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e079210 e-con-full e-flex e-con e-child\" data-id=\"e079210\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa08dc6 elementor-widget elementor-widget-heading\" data-id=\"fa08dc6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Factory smart industry robot arms digital production\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7041d0d e-con-full e-flex e-con e-child\" data-id=\"7041d0d\" data-element_type=\"container\">\n\t\t \t\t<div class=\"elementor-element elementor-element-958b023 elementor-widget elementor-widget-text-editor\" data-id=\"958b023\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tSpanish mackerel yellow weaver sixgill sandperch flyingfish yellowfin cutthroat trout grouper whitebait horsefi. Walleye poolfish sand goby butterfly.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e61219 elementor-widget elementor-widget-text-editor\" data-id=\"2e61219\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNemo enim ipsam voluptatem quia voluptas sit aspernatur aut odit aut fugit, sed quia consequuntur magni dolores eos qui ratione voluptatem sequi nesciunt. Neque porro quisquam est, qui dolorem ipsum quia dolor sit amet, consectetur, adipisci velit, sed quia non numquam eius modi tempora incidunt ut labore et dolore magnam aliquam quaerat voluptatem.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44aec5f elementor-widget elementor-widget-text-editor\" data-id=\"44aec5f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tUt enim ad minima veniam, quis nostrum exercitationem ullam corporis suscipit laboriosam, nisi ut aliquid ex ea commodi consequatur? Quis autem vel eum iure reprehenderit qui in ea voluptate velit esse quam nihil molestiae consequatur, vel illum qui dolorem eum fugiat quo Nemo enim ipsam voluptatem quia voluptas sit aspernatur aut odit aut fugit, sed quia consequuntur magni dolores eos qui ratione voluptatem sequi nesciunt. Neque porro quisquam est.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-533ef47 e-con-full e-flex e-con e-child\" data-id=\"533ef47\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2d46ae7 e-con-full e-flex e-con e-child\" data-id=\"2d46ae7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-804b4df elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"804b4df\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tCompletion Date\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7182abb elementor-widget elementor-widget-text-editor\" data-id=\"7182abb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t25 February 2023\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-83eb12e e-con-full e-flex e-con e-child\" data-id=\"83eb12e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b772228 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"b772228\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tClients\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1bfc30 elementor-widget elementor-widget-text-editor\" data-id=\"b1bfc30\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tQuantum LTD.,\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec8b63d e-con-full e-flex e-con e-child\" data-id=\"ec8b63d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a68795f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a68795f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLocation\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c54b82 elementor-widget elementor-widget-text-editor\" data-id=\"5c54b82\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNebraska Omaha, USA\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d3f65e5 e-con-full e-flex e-con e-child\" data-id=\"d3f65e5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2606e95 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2606e95\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tCategory\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b902ad elementor-widget elementor-widget-text-editor\" data-id=\"9b902ad\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tIndustry &#038; Factory\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-172a6f5 e-con-full e-flex e-con e-child\" data-id=\"172a6f5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32802f7 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"32802f7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tBudget\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f79835a elementor-widget elementor-widget-text-editor\" data-id=\"f79835a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t$16 Million\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2493097 e-flex e-con-boxed e-con e-parent\" data-id=\"2493097\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b1672a elementor-widget elementor-widget-image\" data-id=\"1b1672a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1350\" height=\"640\" src=\"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-content\/uploads\/2024\/07\/demo-content05.jpg\" class=\"attachment-full size-full wp-image-786\" alt=\"\" srcset=\"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-content\/uploads\/2024\/07\/demo-content05.jpg 1350w, https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-content\/uploads\/2024\/07\/demo-content05-1000x474.jpg 1000w, https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-content\/uploads\/2024\/07\/demo-content05-300x142.jpg 300w, https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-content\/uploads\/2024\/07\/demo-content05-1024x485.jpg 1024w, https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-content\/uploads\/2024\/07\/demo-content05-768x364.jpg 768w, https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-content\/uploads\/2024\/07\/demo-content05-770x365.jpg 770w\" sizes=\"(max-width: 1350px) 100vw, 1350px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e15ea20 e-flex e-con-boxed e-con e-parent\" data-id=\"e15ea20\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-efd831e e-con-full e-flex e-con e-child\" data-id=\"efd831e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c8bc88 elementor-widget elementor-widget-heading\" data-id=\"4c8bc88\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Build, streamline and evolve together with solution\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c97a5d e-con-full e-flex e-con e-child\" data-id=\"4c97a5d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a464194 elementor-widget elementor-widget-text-editor\" data-id=\"a464194\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAlways ready to push the boundaries, especially when it comes to our own platform, Our analytical eye to create a site that was visually engaging and also optimised for maximum performance. It also perfectly reflects the journey to help it tell a story to increase its understanding and drive action. To create a site that was visually engaging for maximum performance.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6854030 elementor-mobile_extra-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6854030\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"industras-icon- industras-icon-plus\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Prepare Documentation<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"industras-icon- industras-icon-plus\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Brand Consistency<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"industras-icon- industras-icon-plus\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Quality Control System<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"industras-icon- industras-icon-plus\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Organise everything early thoroughly<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"industras-icon- industras-icon-plus\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Highest Standards in Cost Control<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c935c95 e-flex e-con-boxed e-con e-parent\" data-id=\"c935c95\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4e74b40 e-con-full e-flex e-con e-child\" data-id=\"4e74b40\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-adff1b2 elementor-widget elementor-widget-image\" data-id=\"adff1b2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"660\" height=\"412\" src=\"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-content\/uploads\/2024\/07\/demo-content06.jpg\" class=\"attachment-full size-full wp-image-787\" alt=\"\" srcset=\"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-content\/uploads\/2024\/07\/demo-content06.jpg 660w, https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-content\/uploads\/2024\/07\/demo-content06-300x187.jpg 300w, https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-content\/uploads\/2024\/07\/demo-content06-600x375.jpg 600w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-82a7020 e-con-full e-flex e-con e-child\" data-id=\"82a7020\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-778aaab elementor-widget elementor-widget-image\" data-id=\"778aaab\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"660\" height=\"412\" src=\"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-content\/uploads\/2024\/07\/demo-content07.jpg\" class=\"attachment-full size-full wp-image-788\" alt=\"\" srcset=\"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-content\/uploads\/2024\/07\/demo-content07.jpg 660w, https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-content\/uploads\/2024\/07\/demo-content07-300x187.jpg 300w, https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-content\/uploads\/2024\/07\/demo-content07-600x375.jpg 600w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9d5f2c7 e-flex e-con-boxed e-con e-parent\" data-id=\"9d5f2c7\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-96918db e-con-full e-flex e-con e-child\" data-id=\"96918db\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f026c7f elementor-widget__width-initial elementor-widget-mobile_extra__width-inherit elementor-widget elementor-widget-heading\" data-id=\"f026c7f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">How to Manage your Industrial Projects\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0efc60d e-con-full e-flex e-con e-child\" data-id=\"0efc60d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e2bd3c3 e-con-full e-flex e-con e-child\" data-id=\"e2bd3c3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9fbdcce elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-icon-box\" data-id=\"9fbdcce\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    \t\t<div class=\"elementor-icon-box-wrapper\">\n    \t\t\t    \t\t\t<div class=\"elementor-icon-box-content\">\n    \t\t\t\t<h3 class=\"elementor-icon-box-title\">\n    \t\t\t\t\t<span  >\n    \t\t\t\t\t\tDesign Your Project    \t\t\t\t\t<\/span>\n    \t\t\t\t<\/h3>\n    \t\t\t\t    \t\t\t\t\t<p class=\"elementor-icon-box-description\">\n    \t\t\t\t\t\tUt enim ad minima veniam, quis nostrum exercitationem ullam corporis suscipit laboriosam    \t\t\t\t\t<\/p>\n    \t\t\t\t    \t\t\t<\/div>\n\n    \t\t<\/div>\n    \t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab892ba elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-icon-box\" data-id=\"ab892ba\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    \t\t<div class=\"elementor-icon-box-wrapper\">\n    \t\t\t    \t\t\t<div class=\"elementor-icon-box-content\">\n    \t\t\t\t<h3 class=\"elementor-icon-box-title\">\n    \t\t\t\t\t<span  >\n    \t\t\t\t\t\tProject Testing    \t\t\t\t\t<\/span>\n    \t\t\t\t<\/h3>\n    \t\t\t\t    \t\t\t\t\t<p class=\"elementor-icon-box-description\">\n    \t\t\t\t\t\tUt enim ad minima veniam, quis nostrum exercitationem ullam corporis suscipit laboriosam    \t\t\t\t\t<\/p>\n    \t\t\t\t    \t\t\t<\/div>\n\n    \t\t<\/div>\n    \t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c1b455 elementor-widget__width-initial elementor-widget-tablet_extra__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-icon-box\" data-id=\"9c1b455\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    \t\t<div class=\"elementor-icon-box-wrapper\">\n    \t\t\t    \t\t\t<div class=\"elementor-icon-box-content\">\n    \t\t\t\t<h3 class=\"elementor-icon-box-title\">\n    \t\t\t\t\t<span  >\n    \t\t\t\t\t\tProject Planning    \t\t\t\t\t<\/span>\n    \t\t\t\t<\/h3>\n    \t\t\t\t    \t\t\t\t\t<p class=\"elementor-icon-box-description\">\n    \t\t\t\t\t\tUt enim ad minima veniam, quis nostrum exercitationem ullam corporis suscipit laboriosam    \t\t\t\t\t<\/p>\n    \t\t\t\t    \t\t\t<\/div>\n\n    \t\t<\/div>\n    \t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7af1849 elementor-widget__width-initial elementor-widget-tablet_extra__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-icon-box\" data-id=\"7af1849\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    \t\t<div class=\"elementor-icon-box-wrapper\">\n    \t\t\t    \t\t\t<div class=\"elementor-icon-box-content\">\n    \t\t\t\t<h3 class=\"elementor-icon-box-title\">\n    \t\t\t\t\t<span  >\n    \t\t\t\t\t\tFinal Results    \t\t\t\t\t<\/span>\n    \t\t\t\t<\/h3>\n    \t\t\t\t    \t\t\t\t\t<p class=\"elementor-icon-box-description\">\n    \t\t\t\t\t\tUt enim ad minima veniam, quis nostrum exercitationem ullam corporis suscipit laboriosam    \t\t\t\t\t<\/p>\n    \t\t\t\t    \t\t\t<\/div>\n\n    \t\t<\/div>\n    \t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-018323c elementor-widget elementor-widget-text-editor\" data-id=\"018323c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAlways ready to push the boundaries, especially when it comes to our own platform, Our analytical eye to create a site that was visually engaging and also optimised for maximum performance. It also perfectly reflects the journey to help it tell a story to increase its understanding and drive action. To create a site that was visually engaging for maximum performance.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Factory smart industry robot arms digital production Spanish mackerel yellow weaver sixgill sandperch flyingfish yellowfin cutthroat trout grouper whitebait horsefi. Walleye poolfish sand goby butterfly.Nemo enim ipsam voluptatem quia voluptas sit aspernatur aut odit aut fugit, sed quia consequuntur magni dolores eos qui ratione voluptatem sequi nesciunt. Neque porro quisquam est, qui dolorem ipsum quia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7767,"template":"","class_list":["post-770","project","type-project","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-json\/wp\/v2\/project\/770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-json\/wp\/v2\/media\/7767"}],"wp:attachment":[{"href":"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-json\/wp\/v2\/media?parent=770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}