{"id":8353,"date":"2025-05-08T14:47:58","date_gmt":"2025-05-08T18:47:58","guid":{"rendered":"https:\/\/conceptsk1.com\/filtrationlab-dev\/?post_type=filtre&#038;p=8353"},"modified":"2025-05-08T14:47:58","modified_gmt":"2025-05-08T18:47:58","slug":"les-systemes-dacces-par-le-cote-a-haute-efficacite-haute-pression","status":"publish","type":"filtre","link":"https:\/\/conceptsk1.com\/filtrationlab-dev\/filtre\/les-systemes-dacces-par-le-cote-a-haute-efficacite-haute-pression\/","title":{"rendered":"Les syst\u00e8mes d&rsquo;acc\u00e8s par le c\u00f4t\u00e9 \u00e0 haute efficacit\u00e9 &#038; haute pression"},"featured_media":0,"parent":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"application":[80,79],"categorie-de-filtres":[95],"class_list":["post-8353","filtre","type-filtre","status-publish","hentry","application-commerciale-legere","application-residentielle","categorie-de-filtres-boitiers-pre-usines"],"acf":[],"_links":{"self":[{"href":"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-json\/wp\/v2\/filtre\/8353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-json\/wp\/v2\/filtre"}],"about":[{"href":"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-json\/wp\/v2\/types\/filtre"}],"wp:attachment":[{"href":"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-json\/wp\/v2\/media?parent=8353"}],"wp:term":[{"taxonomy":"application","embeddable":true,"href":"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-json\/wp\/v2\/application?post=8353"},{"taxonomy":"categorie-de-filtres","embeddable":true,"href":"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-json\/wp\/v2\/categorie-de-filtres?post=8353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}