{"id":8255,"date":"2025-05-08T14:01:48","date_gmt":"2025-05-08T18:01:48","guid":{"rendered":"https:\/\/conceptsk1.com\/filtrationlab-dev\/?post_type=filtre&#038;p=8255"},"modified":"2025-05-08T14:01:48","modified_gmt":"2025-05-08T18:01:48","slug":"les-plisses-co","status":"publish","type":"filtre","link":"https:\/\/conceptsk1.com\/filtrationlab-dev\/filtre\/les-plisses-co\/","title":{"rendered":"Les pliss\u00e9s CO"},"featured_media":0,"parent":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"application":[80,79],"categorie-de-filtres":[92],"class_list":["post-8255","filtre","type-filtre","status-publish","hentry","application-commerciale-legere","application-residentielle","categorie-de-filtres-controle-dodeur"],"acf":[],"_links":{"self":[{"href":"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-json\/wp\/v2\/filtre\/8255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-json\/wp\/v2\/filtre"}],"about":[{"href":"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-json\/wp\/v2\/types\/filtre"}],"wp:attachment":[{"href":"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-json\/wp\/v2\/media?parent=8255"}],"wp:term":[{"taxonomy":"application","embeddable":true,"href":"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-json\/wp\/v2\/application?post=8255"},{"taxonomy":"categorie-de-filtres","embeddable":true,"href":"https:\/\/conceptsk1.com\/filtrationlab-dev\/wp-json\/wp\/v2\/categorie-de-filtres?post=8255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}